{"id":189,"date":"2017-05-23T17:16:14","date_gmt":"2017-05-23T17:16:14","guid":{"rendered":"http:\/\/www.eckerd.space\/wiesel\/?p=189"},"modified":"2017-05-23T17:16:14","modified_gmt":"2017-05-23T17:16:14","slug":"becky-blitch-02","status":"publish","type":"post","link":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/","title":{"rendered":"Becky Blitch \u201902"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]I was so blessed to be among the 20 students chosen for Drs. Wiesel and Johnston\u2019s Winter Term in 2000, and it was one of my defining experiences as an Eckerd student. Now it\u2019s upon all of us who learned from him to continue passing along what he taught us.<\/p>\n<p style=\"text-align: right\"><strong>\u00a0<\/strong><strong>\u2014Becky Blitch \u201902 <\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]I was so blessed to be among the 20 students chosen for Drs. Wiesel and Johnston\u2019s Winter Term in 2000, and it was one of my defining experiences as&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-189","post","type-post","status-publish","format-standard","category-00-09"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Becky Blitch \u201902 - Elie Wiesel | Eckerd College<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Becky Blitch \u201902\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]I was so blessed to be among the 20 students chosen for Drs. Wiesel and Johnston\u2019s Winter Term in 2000, and it was one of my defining experiences as...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Elie Wiesel | Eckerd College\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-23T17:16:14+00:00\" \/>\n<meta name=\"author\" content=\"Michel Fougeres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel Fougeres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/\"},\"author\":{\"name\":\"Michel Fougeres\",\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/#\\\/schema\\\/person\\\/55a7ba628da4e516752990ec80107685\"},\"headline\":\"Becky Blitch \u201902\",\"datePublished\":\"2017-05-23T17:16:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/\"},\"wordCount\":121,\"commentCount\":0,\"articleSection\":[\"Classes of 2000-2009\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/\",\"url\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/\",\"name\":\"Becky Blitch \u201902 - Elie Wiesel | Eckerd College\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/#website\"},\"datePublished\":\"2017-05-23T17:16:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/#\\\/schema\\\/person\\\/55a7ba628da4e516752990ec80107685\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/2017\\\/05\\\/23\\\/becky-blitch-02\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/#website\",\"url\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/\",\"name\":\"Elie Wiesel | Eckerd College\",\"description\":\"A Tribute to Elie Wiesel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/#\\\/schema\\\/person\\\/55a7ba628da4e516752990ec80107685\",\"name\":\"Michel Fougeres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g\",\"caption\":\"Michel Fougeres\"},\"url\":\"https:\\\/\\\/www.eckerd.edu\\\/wiesel\\\/author\\\/fougermw\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Becky Blitch \u201902 - Elie Wiesel | Eckerd College","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/","og_locale":"en_US","og_type":"article","og_title":"Becky Blitch \u201902","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]I was so blessed to be among the 20 students chosen for Drs. Wiesel and Johnston\u2019s Winter Term in 2000, and it was one of my defining experiences as...","og_url":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/","og_site_name":"Elie Wiesel | Eckerd College","article_published_time":"2017-05-23T17:16:14+00:00","author":"Michel Fougeres","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michel Fougeres","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/#article","isPartOf":{"@id":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/"},"author":{"name":"Michel Fougeres","@id":"https:\/\/www.eckerd.edu\/wiesel\/#\/schema\/person\/55a7ba628da4e516752990ec80107685"},"headline":"Becky Blitch \u201902","datePublished":"2017-05-23T17:16:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/"},"wordCount":121,"commentCount":0,"articleSection":["Classes of 2000-2009"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/","url":"https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/","name":"Becky Blitch \u201902 - Elie Wiesel | Eckerd College","isPartOf":{"@id":"https:\/\/www.eckerd.edu\/wiesel\/#website"},"datePublished":"2017-05-23T17:16:14+00:00","author":{"@id":"https:\/\/www.eckerd.edu\/wiesel\/#\/schema\/person\/55a7ba628da4e516752990ec80107685"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eckerd.edu\/wiesel\/2017\/05\/23\/becky-blitch-02\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.eckerd.edu\/wiesel\/#website","url":"https:\/\/www.eckerd.edu\/wiesel\/","name":"Elie Wiesel | Eckerd College","description":"A Tribute to Elie Wiesel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eckerd.edu\/wiesel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.eckerd.edu\/wiesel\/#\/schema\/person\/55a7ba628da4e516752990ec80107685","name":"Michel Fougeres","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/092e5b0d3dbc11941eef97b5a7f45428acb7f4e4452ac1621201bf755154044c?s=96&d=mm&r=g","caption":"Michel Fougeres"},"url":"https:\/\/www.eckerd.edu\/wiesel\/author\/fougermw\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/posts\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/comments?post=189"}],"version-history":[{"count":0,"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/posts\/189\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/media?parent=189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/categories?post=189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eckerd.edu\/wiesel\/wp-json\/wp\/v2\/tags?post=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}